{"id":503,"date":"2009-05-27T14:36:11","date_gmt":"2009-05-27T12:36:11","guid":{"rendered":"http:\/\/openmtbmap.org\/?p=503"},"modified":"2023-07-01T13:42:14","modified_gmt":"2023-07-01T11:42:14","slug":"welcome","status":"publish","type":"post","link":"https:\/\/www.velomap.org\/de\/garmin\/welcome\/","title":{"rendered":"Warum VeloMap die beste RadKarte ist!"},"content":{"rendered":"<p><\/p>\n<ul>\n<li><strong>Hoher Kontrast<\/strong> Kartendesign optimiert fuer die kleinen Displays (1.8\u201d-4\u201d) von Outdoor GPS. Eigenes Layout mit wenig Kontrast f\u00fcr Planung am PC\/Desktop.<\/li>\n<\/ul>\n<ul type=\"disc\">\n<li><strong>Stra\u00dfentypen - <\/strong> Klar unterschiedene Farben je nach Wegart\/Stra\u00dfe. Br\u00fccken und Tunnel hervorgehoben. Radwege und Radspuren detailliert dargestellt. Pfeile fuer Einbahnstra\u00dfen\u2026 Mehr dazu in der <a href=\"https:\/\/www.velomap.org\/de\/velomaporg\/map-legend\/\">Kartenlegende.<\/a><\/li>\n<\/ul>\n<ul type=\"disc\">\n<li><strong>Fahrradrelevante<\/strong> Informationen hervorgehoben und suchbar. Etwa Trinkwasserbrunnen, City Bike Stationen oder Fahrradshops.<\/li>\n<\/ul>\n<ul type=\"disc\">\n<li><strong>Fahrradrouten<\/strong> nicht nur nach Wichtigkeit unterschiedlich NEBEN der Stra\u00dfe dargestellt, sondern wie auch alle anderen Dargestellten Informationen fuers Autorouting beruecksichtigt. Andere Karten zeigen zwar Fahrradrouten, lassen dafuer aber die Stra\u00dfe weg.<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.velomap.org\/de\/velomaporg\/autorouting\/\"><strong>Navigation<\/strong><\/a> und <a href=\"https:\/\/www.velomap.org\/de\/velomaporg\/plan-routes\/\">Tourenplanung<\/a> \u2013 Hoch ausget\u00fcfteltes Autorouting optimiert fuer Radfahrer (Tour\/Trekking) und Rennradfahrer.<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/www.velomap.org\/de\/tutorials\/install\/\"><strong>Einfache Installation<\/strong><\/a> in Garmin Mapsource, Garmin Basecamp oder Qlandkarte GT um am PC Routen zu planen (dies geht durch das Autorouting auch fuer Wochentouren sehr schnell).<\/li>\n<\/ul>\n<ul>\n<li><strong>Ausfuehrliche Dokumentation<\/strong> \u2013 alles Wissenswerte zur Benutzung der Karten findet sich auf VeloMap.org<\/li>\n<\/ul>\n<ul>\n<li><strong>H\u00f6henkonturlinien<\/strong> basierend auf viewfinderpanoramas.org Daten \u2013 integriert bei fast allen L\u00e4ndern. Deutlich h\u00f6here Qualit\u00e4t wie die normal benutzten \u201evoid filled SRTM3\" Daten.<\/li>\n<\/ul>\n<ul>\n<li><strong>\"Wei\u00dfe Karte\" oder fehlender Fahrradweg?<\/strong> Jeder kann <a href=\"https:\/\/www.velomap.org\/de\/tutorials\/participate\/\">teilnehmen<\/a> und die fehlenden Daten in Openstreetmap hinzufuegen. Zum w\u00f6chentlichen Kartenupdate werden immer die neuesten Daten aus Openstreetmap ber\u00fccksichtigt. So werden die Karten Woche f\u00fcr Woche besser und kompletter. Wird eine in Openstreetmap ber\u00fccksichtigte Information die f\u00fcr Fahrradfahrer wichtig nicht dargestellt? Einfach Kommentar schreiben und ich werde es wenn m\u00f6glich einbauen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Das erste mal hier, oder gerade erste Erfahrungen mit dem GPS gemacht?<\/h3>\n<p>Hier gibt es eine \u00dcbersicht wie man loslegt - <a href=\"https:\/\/www.velomap.org\/de\/tutorials\/enbeginners-starting-guide-dewo-beginnen-tutorial\/\">Anf\u00e4ngerguide<\/a><\/p>\n<h3>\u00a0<\/h3>\n<h3>Karten-Layout<\/h3>\n<p>Die Karten sind optimiert auf die kleinen Displays der OutdoorGPS und daher sehr <a href=\"https:\/\/www.velomap.org\/velomaporg\/screenshots\/\">Kontrastreich<\/a>. Schlie\u00dflich will man auch bei Licht\/Schattenwechsel nich nur sicher erkennen k\u00f6nnen wo es langgeht, sondern auch wie der Wegzustand ist, oder um was f\u00fcr eine Stra\u00dfe es sich handelt. Da am Desktop die kontrastreiche Darstellung suboptimal ist, gibt es ein eigenes Layout zum planen am PC (mit Basecamp, Mapsource oder Qlandkarte GT). Genauer sieht man das an der <a href=\"https:\/\/www.velomap.org\/de\/velomaporg\/map-legend\/\">Kartenlegende<\/a><\/p>\n<p>\u00a0 <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.velomap.org\/wp-content\/uploads\/images\/velomap3.png\" alt=\"\" width=\"800\" height=\"423\" align=\"middle\" \/><\/p>\n<h3>\u00a0<\/h3>\n<p>&nbsp;<\/p>\n<h3>Navigation<\/h3>\n<p>Garmin unterst\u00fctzt in allen Programmen und GPS zwei <a href=\"https:\/\/www.velomap.org\/de\/velomaporg\/autorouting\/\">Autoroutingmodi<\/a>. Schnellere Zeit und K\u00fcrzere Strecke. In Verwendung mit den VeloMaps, ist k\u00fcrzere Strecke auch wirklich kurz (im Vergleich zu allen anderen Karten die ich ausprobiert habe), obwohl dabei versucht wird nur auf Nebenstra\u00dfen und Fahrradwegen zu routen. Mit dem Modi Schnellere Zeit, wird dagegen nach dem Motto \"sch\u00f6nste \/ attraktivste\" Strecke geroutet. Da man mit dem Fahrrad deutlich h\u00e4ufiger abbiegt als mit einem Auto, dauert die Berechnung der Route etwas l\u00e4nger als mit Karten f\u00fcr PKW. Am PC mit\u00a0 Mapsource 6.16 oder Basecamp v3 funktioniert Routing ohne Viapunkte bis zu <strong>400km<\/strong>.\u00a0 200-300km sind immerhin auf Nuvi\/Oregon\/Dakota\/new Generation etrex\/GPSmaps m\u00f6glich. Und bis zu 100km auf alten GPS wie Legend\/Vista HCx obwohl prim\u00e4r Nebenstra\u00dfen, Fahrradwege und Fahrradrouten bevorzugt werden (etwa 30-40km wenn eine Gro\u00dfstadt im Weg liegt). Somit kann man mit allen modernen GPS eine Tagesroute ohne Viapunkt berechnen, auf einem Vista HCx, sollte man mit 2-3 Viapunkten auch Tagestouren am GPS selber planen k\u00f6nnen. \u00a0<\/p>\n<h3>Was macht Openstreetmap und damit die VeloMap besonders?<\/h3>\n<p>Herk\u00f6mmliche topographische Karten basieren auf den Daten der Landesvermessungs\u00e4mter. Deren Daten sind oft schon vor Jahrzehnten aufgenommen worden. Sie\u00a0sind fuer GPS Ger\u00e4te in der Lagegenauigkeit ungen\u00fcgend, und vor allem fokussieren sie\u00a0hautps\u00e4chlich Wanderer. Zum Rennradfahren oder Fahrradfahren fehlen aber die relevanten Informationen, damit man wei\u00df, ob man einen Weg fahren kann oder nicht.\u00a0 In Openstreetmap dagegen werden solche Daten eingetragen. Die Karten zeigen daher zus\u00e4tzliche Weginformationen, wie Fahrradspuren und Fahrradwege neben Stra\u00dfen , Einbahnstra\u00dfenpfeile, Fahrradrouten, Wegzustand,.....<\/p>\n<h4>Jeder kann Mitmachen und die Karten vebessern!:<\/h4>\n<p align=\"left\">Wenn Wege oder sonstige Daten in den Karten fehlen, dann surfe zu <a href=\"https:\/\/www.openstreetmap.org\/\">www.openstreetmap.org<\/a> und erg\u00e4nze die fehlenden Informationen, Stra\u00dfen, Wege, Gleise, POI.... <a class=\"linkification-ext\" title=\"Linkification: https:\/\/www.velomap.org\/de\/tutorials\/participate\/\" href=\"https:\/\/www.velomap.org\/de\/tutorials\/participate\/\">auf der Tagging Anleitung<\/a> gibt es eine \u00dcbersicht wie man die Fahrradrelevanten Informationen in \"OSM eintr\u00e4gt\"<\/p>\n<h3>F\u00fcr wen sind diese Karten gedacht?<\/h3>\n<p align=\"left\">Prim\u00e4r Fahrradfahrer und Rennradfahrer, die \u00fcbersichtliche und detailreiche Fahrradkarten suchen. Umso mehr nat\u00fcrlich f\u00fcr Besitzer von Garmin GPS, oder PDA Besitzer, die Garmin Mobile XT installiert haben - welches die Karten auch benutzen kann.<\/p>\n<p align=\"left\">Jedoch ist das Besitzen von Garmin Ger\u00e4ten nicht erforderlich. Neben der kostenlosen Software Garmin Basecamp oder Garmin Mapsource kann auch <a class=\"linkification-ext\" title=\"Linkification: http:\/\/www.qlandkarte.org\" href=\"http:\/\/www.qlandkarte.org\">www.qlandkarte.org<\/a> die Karten hervorragend darstellen bzw. sogar \u00fcber Rasterkarten transparent darstellen (nur unterst\u00fctzt es leider noch kein Autorouting).<\/p>\n<h3>Du bist Mountainbiker oder Wanderer und suchst Karten?<\/h3>\n<p align=\"left\">Dann bist du auf <a href=\"https:\/\/openmtbmap.org\">OpenMTBMap.org<\/a> genau richtig! Die OpenMTBMaps zeigen detaillierte Infos ob man etwa einen Trail nur bergab befahren kann, oder auch bergauf, und welche Schwierigkeiten man zu erwarten hat. Dazu sind die Wegeklassifizierungen noch deutlich detaillierter wie auf der VeloMap Karte. Das Autorouting dabei nicht auf Nebenstra\u00dfen, sondern MTB Strecken und Singletrails spezialisiert.<\/p>\n<p align=\"left\">\u00a0<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<\/p>\n<p> Hoher Kontrast Kartendesign optimiert fuer die kleinen Displays (1.8\u201d-4\u201d) von Outdoor GPS. Eigenes Layout mit wenig Kontrast f\u00fcr Planung am PC\/Desktop. Stra\u00dfentypen &#8211; Klar unterschiedene Farben je nach Wegart\/Stra\u00dfe. Br\u00fccken und Tunnel hervorgehoben. Radwege und Radspuren detailliert dargestellt. Pfeile fuer Einbahnstra\u00dfen\u2026 Mehr dazu in der Kartenlegende. Fahrradrelevante Informationen hervorgehoben und suchbar. Etwa Trinkwasserbrunnen, City Bike Stationen oder Fahrradshops. Fahrradrouten nicht nur nach Wichtigkeit unterschiedlich NEBEN der Stra\u00dfe dargestellt, sondern wie auch alle anderen Dargestellten Informationen fuers Autorouting beruecksichtigt. Andere Karten zeigen zwar Fahrradrouten, lassen dafuer aber die Stra\u00dfe weg. Navigation und Tourenplanung \u2013 Hoch ausget\u00fcfteltes Autorouting optimiert fuer Radfahrer (Tour\/Trekking) und Rennradfahrer. Einfache Installation in Garmin Mapsource, Garmin Basecamp oder Qlandkarte GT um am PC Routen zu planen (dies geht durch das Autorouting auch fuer Wochentouren sehr schnell). Ausfuehrliche Dokumentation \u2013 alles Wissenswerte zur Benutzung der Karten findet sich auf VeloMap.org H\u00f6henkonturlinien basierend auf viewfinderpanoramas.org Daten \u2013 integriert bei fast allen L\u00e4ndern. Deutlich h\u00f6here Qualit\u00e4t wie die normal benutzten \u201evoid filled SRTM3&#8243; Daten. &#8220;Wei\u00dfe Karte&#8221; oder fehlender Fahrradweg? Jeder kann teilnehmen und die fehlenden Daten in Openstreetmap hinzufuegen. Zum w\u00f6chentlichen Kartenupdate werden immer die neuesten Daten aus Openstreetmap ber\u00fccksichtigt. So werden die Karten Woche f\u00fcr Woche besser und kompletter. [&#8230;]<\/p>\n","protected":false},"author":2561,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,32],"tags":[10,39,12,15,16,18,21,22,24,26,31,41],"class_list":["post-503","post","type-post","status-publish","format-standard","hentry","category-garmin","category-qlandkarte-gt","tag-free","tag-garmin","tag-gps","tag-karten","tag-maps","tag-mapsource","tag-mountainbike","tag-mtb","tag-openstreetmap","tag-osm","tag-qlandkarte","tag-qlandkarte-gt","odd"],"_links":{"self":[{"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/posts\/503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/users\/2561"}],"replies":[{"embeddable":true,"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/comments?post=503"}],"version-history":[{"count":0,"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/posts\/503\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/media?parent=503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/categories?post=503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.velomap.org\/de\/wp-json\/wp\/v2\/tags?post=503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}